{"id":828,"date":"2019-02-09T10:52:31","date_gmt":"2019-02-09T10:52:31","guid":{"rendered":"http:\/\/mediawolf.fi\/?page_id=828"},"modified":"2026-04-21T09:51:48","modified_gmt":"2026-04-21T09:51:48","slug":"mainossuunnittelu","status":"publish","type":"page","link":"https:\/\/mediawolf.fi\/fi\/mainossuunnittelu\/","title":{"rendered":"Mainossuunnittelu"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; admin_label=&#8221;V\u00e4lkommmen&#8221; _builder_version=&#8221;4.20.2&#8243; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; top_divider_color=&#8221;#ffffff&#8221; top_divider_height=&#8221;80px&#8221; bottom_divider_style=&#8221;waves2&#8243; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_height=&#8221;8vw&#8221; divi_se_set=&#8221;proparticles&#8221; divi_se_proparticles_transform=&#8221;divi_se_proparticles&#8221; divi_se_proparticles_particlescolor=&#8221;#b3b3b3&#8243; divi_se_proparticles_linescolor=&#8221;#8f8f8f&#8221; divi_se_proparticles_speed=&#8221;2&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_fullwidth_slider _builder_version=&#8221;4.24.3&#8243; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#ffffff&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;19px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset6&#8243; box_shadow_blur=&#8221;10px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.1)&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_text_size__hover=&#8221;null&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover=&#8221;null&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover=&#8221;null&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_text_color__hover=&#8221;null&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover=&#8221;null&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover=&#8221;null&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_border_width__hover=&#8221;null&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover=&#8221;null&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover=&#8221;null&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_border_color__hover=&#8221;null&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover=&#8221;null&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover=&#8221;null&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_border_radius__hover=&#8221;null&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover=&#8221;null&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover=&#8221;null&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover=&#8221;null&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover=&#8221;null&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover=&#8221;null&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_bg_color__hover=&#8221;null&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover=&#8221;null&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover=&#8221;null&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_slide _builder_version=&#8221;4.24.3&#8243; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;67px&#8221; header_line_height=&#8221;1.1em&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_font_size=&#8221;27px&#8221; body_line_height=&#8221;2.5em&#8221; background_color=&#8221;#ffffff&#8221; background_image=&#8221;https:\/\/mediawolf.fi\/wp-content\/uploads\/2018\/06\/StudioBG.jpg&#8221; header_font_size_tablet=&#8221;51px&#8221; header_font_size_phone=&#8221;31px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;17px&#8221; body_font_size_phone=&#8221;13px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;&#8221; body_line_height_phone=&#8221;&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; sticky_transition=&#8221;on&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||4em|&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;75%&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;TV &amp; elokuvatuotanto&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe024;||divi||400&#8243; icon_color=&#8221;#db2782&#8243; admin_label=&#8221;Videoproduktion&#8221; module_class=&#8221;blurb-3&#8243; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;17px&#8221; custom_margin=&#8221;|-20px||-20px&#8221; filter_opacity=&#8221;30%&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjM4MCJ9fQ==@&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; _dynamic_attributes=&#8221;link_option_url&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_blurb][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;Monikamera- tuotanto ja suoratoisto&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe602;||divi||400&#8243; icon_color=&#8221;#db2782&#8243; admin_label=&#8221;Flerkamera- produktion &#038; streaming&#8221; module_class=&#8221;blurb-3&#8243; _builder_version=&#8221;4.27.6&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;17px&#8221; filter_opacity=&#8221;30%&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMwOTUifX0=@&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;75%&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;Web-suunnittelu&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe00e;||divi||400&#8243; icon_color=&#8221;#db2782&#8243; admin_label=&#8221;Webbdesign&#8221; module_class=&#8221;blurb-3&#8243; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;17px&#8221; filter_opacity=&#8221;30%&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;\/fi\/web-suunnittelu\/&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;Mainossuunnittelu&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe103;||divi||400&#8243; icon_color=&#8221;#db2782&#8243; admin_label=&#8221;Reklamplanering&#8221; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;17px&#8221; animation=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;75%&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_blurb title=&#8221;Valokuvaus&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe00f;||divi||400&#8243; icon_color=&#8221;#db2782&#8243; admin_label=&#8221;Fotografering&#8221; module_class=&#8221;blurb-3&#8243; _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;17px&#8221; filter_opacity=&#8221;30%&#8221; animation=&#8221;off&#8221; link_option_url=&#8221;\/fi\/valokuvaus\/&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; parallax__hover=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#083583&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h1>N\u00e4kyv\u00e4\u00e4 mainontaa \u2013 digitaalisesti ja painettuna<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#083583&#8243; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||0px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Toteutamme kaikkea k\u00e4yntikorteista, flyereist\u00e4 ja esitteist\u00e4 sanomalehtimainoksiin, julisteisiin, banderolleihin, roll-upeihin ja kokonaisiin messuosastoihin. Yhdess\u00e4 yhteisty\u00f6kumppaneidemme kanssa huolehdimme koko prosessista \u2013 suunnittelusta valmiiseen tuotteeseen.<\/p>\n<p><\/p>\n<p>Ymp\u00e4rist\u00f6 on meille \u2013 ja sinulle \u2013 t\u00e4rke\u00e4\u00e4. Siksi teemme yhteisty\u00f6t\u00e4 Pohjoismaisesti ymp\u00e4rist\u00f6merkittyjen painotalojen kanssa Suomessa, jotka keskittyv\u00e4t kest\u00e4v\u00e4\u00e4n ja ymp\u00e4rist\u00f6yst\u00e4v\u00e4lliseen tuotantoon.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e4kyv\u00e4\u00e4 mainontaa \u2013 digitaalisesti ja painettunaToteutamme kaikkea k\u00e4yntikorteista, flyereist\u00e4 ja esitteist\u00e4 sanomalehtimainoksiin, julisteisiin, banderolleihin, roll-upeihin ja kokonaisiin messuosastoihin. Yhdess\u00e4 yhteisty\u00f6kumppaneidemme kanssa huolehdimme koko prosessista \u2013 suunnittelusta valmiiseen tuotteeseen.Ymp\u00e4rist\u00f6 on meille \u2013 ja sinulle \u2013 t\u00e4rke\u00e4\u00e4. Siksi teemme yhteisty\u00f6t\u00e4 Pohjoismaisesti ymp\u00e4rist\u00f6merkittyjen painotalojen kanssa Suomessa, jotka keskittyv\u00e4t kest\u00e4v\u00e4\u00e4n ja ymp\u00e4rist\u00f6yst\u00e4v\u00e4lliseen tuotantoon.<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-828","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/pages\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":5,"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/pages\/828\/revisions"}],"predecessor-version":[{"id":6321,"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/pages\/828\/revisions\/6321"}],"wp:attachment":[{"href":"https:\/\/mediawolf.fi\/fi\/wp-json\/wp\/v2\/media?parent=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}